{"id":179138,"date":"2026-03-11T11:33:21","date_gmt":"2026-03-11T14:33:21","guid":{"rendered":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/?p=179138"},"modified":"2026-03-11T12:33:15","modified_gmt":"2026-03-11T15:33:15","slug":"conflito-selecao-do-ira-nao-participara-da-copa-do-mundo-afirma-ministro-do-esporte","status":"publish","type":"post","link":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/2026\/03\/11\/conflito-selecao-do-ira-nao-participara-da-copa-do-mundo-afirma-ministro-do-esporte\/","title":{"rendered":"Conflito: Sele\u00e7\u00e3o do Ir\u00e3 n\u00e3o participar\u00e1 da Copa do Mundo, afirma ministro do Esporte"},"content":{"rendered":"<div class=\"styles__Body-sc-1ffquwr-7 ePhtZb\">\n<h4>O ministro do Esporte do Ir\u00e3, Ahmad Donyamali, declarou nesta quarta-feira (11) que o pa\u00eds n\u00e3o deve participar da Copa do Mundo FIFA 2026, que ser\u00e1 realizada em Estados Unidos, Canad\u00e1 e M\u00e9xico. Em entrevista \u00e0 televis\u00e3o estatal iraniana, ele criticou duramente o governo americano.<\/h4>\n<h4>&#8220;Considerando que este regime corrupto (os EUA) assassinou nosso l\u00edder, sob nenhuma circunst\u00e2ncia poderemos participar da Copa do Mundo&#8221;, afirmou Donyamali.<\/h4>\n<h4>Apesar das declara\u00e7\u00f5es do ministro, a decis\u00e3o oficial sobre a presen\u00e7a da sele\u00e7\u00e3o iraniana no Mundial cabe \u00e0 Federa\u00e7\u00e3o de Futebol da Rep\u00fablica Isl\u00e2mica do Ir\u00e3. O presidente da entidade, Mehdi Taj, tamb\u00e9m tem demonstrado d\u00favidas sobre a participa\u00e7\u00e3o da equipe na competi\u00e7\u00e3o.<\/h4>\n<h4>&#8220;Se durante a Copa do Mundo estiver assim, quem em s\u00e3 consci\u00eancia enviaria sua sele\u00e7\u00e3o para um lugar desses?&#8221;, disse.<\/h4>\n<h4 data-end=\"534\" data-start=\"178\">O presidente da Fifa, Gianni Infantino, afirmou nesta quarta-feira (11) que o presidente dos Estados Unidos, Donald Trump, prometeu que a sele\u00e7\u00e3o do Ir\u00e3 ser\u00e1 recebida sem obst\u00e1culos para disputar a Copa do Mundo de 2026. Segundo o dirigente, a garantia foi dada durante uma conversa entre os dois e indica que a equipe iraniana ser\u00e1 bem-vinda no pa\u00eds-sede.<\/h4>\n<h4 data-end=\"1017\" data-start=\"536\">Em publica\u00e7\u00e3o nas redes sociais, Infantino mencionou pela primeira vez \u201ca situa\u00e7\u00e3o no Ir\u00e3\u201d, sem detalhar se a incerteza sobre a presen\u00e7a da sele\u00e7\u00e3o no torneio est\u00e1 relacionada aos ataques americanos e israelenses de 28 de fevereiro, que desencadearam uma guerra no Oriente M\u00e9dio. (Metro1).<\/h4>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Esporte do Ir\u00e3, Ahmad Donyamali, declarou nesta quarta-feira (11) que o pa\u00eds n\u00e3o deve participar da Copa do Mundo FIFA 2026, que ser\u00e1 realizada em Estados Unidos, Canad\u00e1 e M\u00e9xico. Em entrevista \u00e0 televis\u00e3o estatal iraniana, ele criticou duramente o governo americano. &#8220;Considerando que este regime corrupto (os EUA) assassinou nosso l\u00edder, sob nenhuma circunst\u00e2ncia poderemos participar da Copa do Mundo&#8221;, afirmou Donyamali. Apesar das declara\u00e7\u00f5es do ministro, a decis\u00e3o oficial sobre a presen\u00e7a da sele\u00e7\u00e3o iraniana no Mundial cabe \u00e0 Federa\u00e7\u00e3o de Futebol da Rep\u00fablica Isl\u00e2mica do Ir\u00e3. O presidente da entidade, Mehdi Taj, tamb\u00e9m tem [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":179139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1261],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/179138"}],"collection":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/comments?post=179138"}],"version-history":[{"count":2,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/179138\/revisions"}],"predecessor-version":[{"id":179141,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/179138\/revisions\/179141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/media\/179139"}],"wp:attachment":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/media?parent=179138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/categories?post=179138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/tags?post=179138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}