{"id":139463,"date":"2021-05-05T22:37:48","date_gmt":"2021-05-06T01:37:48","guid":{"rendered":"http:\/\/www.cronicasdeitarantim.com.br\/v1\/?p=139463"},"modified":"2021-05-05T22:37:48","modified_gmt":"2021-05-06T01:37:48","slug":"detentos-idosos-e-com-comorbidades-sao-vacinados-contra-covid-19-em-presidios-da-bahia-veja-cidades","status":"publish","type":"post","link":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/2021\/05\/05\/detentos-idosos-e-com-comorbidades-sao-vacinados-contra-covid-19-em-presidios-da-bahia-veja-cidades\/","title":{"rendered":"Detentos idosos e com comorbidades s\u00e3o vacinados contra Covid-19 em pres\u00eddios da Bahia, veja cidades"},"content":{"rendered":"<p>Os internos do sistema prisional baiano que se encaixam nos grupos priorit\u00e1rios j\u00e1 vacinados contra Covid-19 tamb\u00e9m receberam o imunizante, mesmo privados de liberdade. A vacina\u00e7\u00e3o foi acompanhada pela Defensoria P\u00fablica do Estado da Bahia (DPE\/BA). Segundo o \u00f3rg\u00e3o, \u00a0no fim do m\u00eas de mar\u00e7o, todos os internos com mais de 59 anos nos conjuntos penais na Bahia j\u00e1 haviam recebido pelo menos uma dose de vacina.<\/p>\n<p>At\u00e9 esta ter\u00e7a-feira (04), 152 internos nos conjuntos prisionais da Bahia, incluindo idosos e algumas pessoas com comorbidades, j\u00e1 haviam sido vacinados \u2013 55 na capital e 97 no interior. Com a chegada da vacina\u00e7\u00e3o para os portadores de comorbidades a DPE seguir\u00e1 acompanhando a vacina\u00e7\u00e3o do novo grupo, tamb\u00e9m nas pris\u00f5es.<\/p>\n<p>\u201cO direito \u00e0 sa\u00fade \u00e9 o mesmo. N\u00e3o \u00e9 porque ela est\u00e1 presa que ela perde a caracter\u00edstica de idoso, ou de pessoa com comorbidade\u201d, explicou o defensor Maur\u00edcio Saporito. \u201cDesde o in\u00edcio da fase priorit\u00e1ria de vacina\u00e7\u00e3o, a Defensoria se movimentou para garantir aos idosos privados de liberdade esse direito, pois \u00e9 um ato de cidadania e civilidade\u201d, pontuou o defensor Pedro Casali, que coordena a Especializada Criminal e de Execu\u00e7\u00e3o Penal da DPE\/BA.<\/p>\n<p>Ao todo, internos de doze cidades baianas j\u00e1 receberam vacinas. Os detentos est\u00e3o distribu\u00eddos da seguinte forma.: Salvador (55); Barreiras (1); Feira de Santana(24); Ilh\u00e9us (13); Itabuna (8); Jequi\u00e9 (8); Juazeiro (8); Paulo Afonso (7); Serrinha (5); Teixeira de Freitas (6); Valen\u00e7a (4); Vit\u00f3ria da Conquista (13). Ainda segundo informa\u00e7\u00f5es da DPE, das 26 unidades prisionais em funcionamento na Bahia, 20 apresentaram casos positivos de Covid-19. O sistema penitenci\u00e1rio registrou, at\u00e9 o momento, 2.441 casos confirmados do novo coronav\u00edrus, sendo 1.432 deles em servidores e 1.009 pessoas privadas de liberdade. Destes, seis foram a \u00f3bito; quatro servidores e dois internos. Fonte: Metro1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os internos do sistema prisional baiano que se encaixam nos grupos priorit\u00e1rios j\u00e1 vacinados contra Covid-19 tamb\u00e9m receberam o imunizante, mesmo privados de liberdade. A vacina\u00e7\u00e3o foi acompanhada pela Defensoria P\u00fablica do Estado da Bahia (DPE\/BA). Segundo o \u00f3rg\u00e3o, \u00a0no fim do m\u00eas de mar\u00e7o, todos os internos com mais de 59 anos nos conjuntos penais na Bahia j\u00e1 haviam recebido pelo menos uma dose de vacina. At\u00e9 esta ter\u00e7a-feira (04), 152 internos nos conjuntos prisionais da Bahia, incluindo idosos e algumas pessoas com comorbidades, j\u00e1 haviam sido vacinados \u2013 55 na capital e 97 no interior. Com a chegada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[295],"tags":[506,676],"_links":{"self":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/139463"}],"collection":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/comments?post=139463"}],"version-history":[{"count":1,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/139463\/revisions"}],"predecessor-version":[{"id":139465,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/posts\/139463\/revisions\/139465"}],"wp:attachment":[{"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/media?parent=139463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/categories?post=139463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cronicasdeitarantim.com.br\/v1\/wp-json\/wp\/v2\/tags?post=139463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}